{"id":91720,"date":"2024-04-24T14:21:09","date_gmt":"2024-04-24T12:21:09","guid":{"rendered":"https:\/\/poppers-online.ch\/produkt\/iron-fist-poppers-etichetta-nera-24ml\/"},"modified":"2026-05-17T13:00:26","modified_gmt":"2026-05-17T11:00:26","slug":"iron-fist-poppers-etichetta-nera-24ml","status":"publish","type":"product","link":"https:\/\/poppers-online.ch\/it\/prodotto\/iron-fist-poppers-etichetta-nera-24ml\/","title":{"rendered":"Iron Fist Poppers Etichetta Nera 24ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><span style=\"font-weight: 400;\">Noi e i nostri amici Fist abbiamo aspettato a lungo questo momento: Il <\/span><b>Iron Fist Poppers Etichetta Nera 24ml <\/b> <span style=\"font-weight: 400;\">\u00e8 presente nella forte formula pentilica e nell&#8217;indistruttibile flacone in alluminio. Questo potente popper \u00e8 dedicato a tutti gli esperti senza paura e agli amanti dei giochi FF e delle sessioni pi\u00f9 impegnative. Una volta aperto, Iron Fist Black Label ti trasforma in un animale sfrenato che desidera cazzi grossi, pugni e giocattoli. Il pratico formato tascabile della bottiglia in alluminio, leggera e indistruttibile, si adatta a ogni tasca dei pantaloni e ti ispirer\u00e0. <\/span><\/p>\n","protected":false},"featured_media":93756,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":61,"_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0},"product_brand":[],"product_cat":[1047,109],"product_tag":[],"class_list":["post-91720","product","type-product","status-publish","has-post-thumbnail","product_cat-popper","product_cat-boccette-grandi","pa_gewindegroesse-piccola","pa_inhalt-24ml","pa_inhaltsstoffe-nitrito-di-alcool-isoamilico","pa_marke-fist-popper","pa_staerke-105","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/product\/91720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/comments?post=91720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/media\/93756"}],"wp:attachment":[{"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/media?parent=91720"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/product_brand?post=91720"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/product_cat?post=91720"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/poppers-online.ch\/it\/wp-json\/wp\/v2\/product_tag?post=91720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}